{"id":6305,"date":"2024-11-04T16:07:05","date_gmt":"2024-11-04T19:07:05","guid":{"rendered":"https:\/\/anparq.org.br\/site\/?p=6305"},"modified":"2024-11-04T16:07:13","modified_gmt":"2024-11-04T19:07:13","slug":"mocao-em-defesa-da-faperj-por-ciencia-tecnologia-e-processos-eticos-com-alto-impacto-social","status":"publish","type":"post","link":"https:\/\/anparq.org.br\/site\/2024\/11\/04\/mocao-em-defesa-da-faperj-por-ciencia-tecnologia-e-processos-eticos-com-alto-impacto-social\/","title":{"rendered":"MO\u00c7\u00c3O EM DEFESA DA FAPERJ POR CI\u00caNCIA, TECNOLOGIA E PROCESSOS \u00c9TICOS COM ALTO IMPACTO SOCIAL\u00a0"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.18.0&#8243; custom_margin=&#8221;0px|0px|0px|0px|true|true&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;et_body_layout&#8221;][et_pb_row _builder_version=&#8221;4.18.0&#8243; background_color=&#8221;#FAF7EE&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; width=&#8221;100%&#8221; custom_margin=&#8221;0px|0px|0px|0px|true|true&#8221; custom_padding=&#8221;0px|5px|0px|5px|true|true&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;et_body_layout&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;et_body_layout&#8221;][et_pb_text _builder_version=&#8221;4.26.0&#8243; text_font=&#8221;|300|||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;2em&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;et_body_layout&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p><span data-contrast=\"auto\">Rio de Janeiro, 25 de outubro de 2024<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Exmo. Sr. Cl\u00e1udio Bomfim de Castro e Silva\u00a0\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Governador do Estado do Rio de Janeiro\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">A Associa\u00e7\u00e3o Nacional de Pesquisa e P\u00f3s-gradua\u00e7\u00e3o em Arquitetura e Urbanismo (ANPARQ) manifesta sua preocupa\u00e7\u00e3o com a recente not\u00edcia, amplamente divulgada, sobre a troca na presid\u00eancia da Funda\u00e7\u00e3o Carlos Chagas Filho de Amparo \u00e0 Pesquisa do Estado do Rio de Janeiro (FAPERJ).\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Considerando<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Que a FAPERJ \u00e9 uma institui\u00e7\u00e3o fundamental para promover o desenvolvimento da pesquisa em ci\u00eancia e tecnologia, sendo uma das mais importantes ag\u00eancias de fomento \u00e0 pesquisa do Brasil;<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Que a lideran\u00e7a do Dr. Jerson Lima da Silva \u00e0 frente da Funda\u00e7\u00e3o \u00e9 essencial para o bom desempenho das institui\u00e7\u00f5es de pesquisa do Estado do Rio de Janeiro, por meio de processos transparentes e competentes, apoiando projetos de grande relev\u00e2ncia, contribuindo para a fixa\u00e7\u00e3o dos pesquisadores no RJ e gerando benef\u00edcios sociais, tecnol\u00f3gicos e econ\u00f4micos inestim\u00e1veis para o pa\u00eds;<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Que a perman\u00eancia do Dr. Jerson Lima da Silva na presid\u00eancia da FAPERJ \u00e9 imprescind\u00edvel para garantir o acompanhamento de um apoio \u00e9tico e competente \u00e0 pesquisa e educa\u00e7\u00e3o em todas as \u00e1reas das ci\u00eancias;\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Vimos, por meio desta MO\u00c7\u00c3O, solicitar respeitosamente ao Exmo. Governador que reconsidere a decis\u00e3o de substituir o Dr. Jerson Lima da Silva na presid\u00eancia da FAPERJ, em benef\u00edcio da comunidade cient\u00edfica, da sociedade fluminense e do avan\u00e7o cont\u00ednuo da ci\u00eancia e tecnologia que promovem a autonomia e a emancipa\u00e7\u00e3o de nosso pa\u00eds.\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Atenciosamente,<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rio de Janeiro, 25 de outubro de 2024\u00a0 \u00a0 Exmo. Sr. Cl\u00e1udio Bomfim de Castro e Silva\u00a0\u00a0\u00a0 Governador do Estado do Rio de Janeiro\u00a0\u00a0 \u00a0 A Associa\u00e7\u00e3o Nacional de Pesquisa e P\u00f3s-gradua\u00e7\u00e3o em Arquitetura e Urbanismo (ANPARQ) manifesta sua preocupa\u00e7\u00e3o com a recente not\u00edcia, amplamente divulgada, sobre a troca na presid\u00eancia da Funda\u00e7\u00e3o Carlos Chagas [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":6306,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-6305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/anparq.org.br\/site\/wp-json\/wp\/v2\/posts\/6305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anparq.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anparq.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anparq.org.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/anparq.org.br\/site\/wp-json\/wp\/v2\/comments?post=6305"}],"version-history":[{"count":2,"href":"https:\/\/anparq.org.br\/site\/wp-json\/wp\/v2\/posts\/6305\/revisions"}],"predecessor-version":[{"id":6309,"href":"https:\/\/anparq.org.br\/site\/wp-json\/wp\/v2\/posts\/6305\/revisions\/6309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anparq.org.br\/site\/wp-json\/wp\/v2\/media\/6306"}],"wp:attachment":[{"href":"https:\/\/anparq.org.br\/site\/wp-json\/wp\/v2\/media?parent=6305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anparq.org.br\/site\/wp-json\/wp\/v2\/categories?post=6305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anparq.org.br\/site\/wp-json\/wp\/v2\/tags?post=6305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}